{"id":120985,"date":"2022-03-18T16:02:19","date_gmt":"2022-03-18T16:02:19","guid":{"rendered":"https:\/\/paratraduccion.com\/limiares\/?p=120985"},"modified":"2022-03-18T16:37:38","modified_gmt":"2022-03-18T16:37:38","slug":"avoo-en-directo-marca-vigo","status":"publish","type":"post","link":"http:\/\/paratraduccion.com\/limiares\/pt\/avoo-en-directo-marca-vigo\/","title":{"rendered":"Avoo en Directo Marca Vigo"},"content":{"rendered":"<p style=\"text-align: justify;\">Hoy, Ismael Men\u00e9ndez y Jacobo Mart\u00ednez han sido entrevistados en el programa\u00a0de radio <em>Directo Marca Vigo\u00a0<\/em> sobre el proyecto del videojuego <em>Avoo<\/em>, desarrollado por la empresa coru\u00f1esa <a href=\"https:\/\/www.iseltec.com\/\" target=\"_blank\" rel=\"noopener\">Iseltec<\/a>\u00a0con la colaboraci\u00f3n de la <a href=\"http:\/\/muvi.gal\/\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n Museo do Videoxogo de Galicia (MUVI)<\/a> y el T\u00edtulo Propio de <strong>E<\/strong>specialista em <strong>T<\/strong>raducci\u00f3n para la <strong>I<\/strong>nd\u00fastria de <strong>V<\/strong>ideojuego (ETIV) de nuestro\u00a0<strong>M<\/strong>estrado em <strong>T<\/strong>raducci\u00f3n para la <strong>C<\/strong>omunica\u00e7\u00e3o <strong>I<\/strong>nternacional (MTCI) de la Universidad de Vigo (UVigo), <strong>MESTRADO UNIVERSIT\u00c1RIO COM EXCEL\u00caNCIA DA XUNTA DE GALICIA<\/strong>.<\/p>\n<div id=\"attachment_120986\" style=\"width: 926px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-120986\" class=\"wp-image-120986 size-full\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/03\/AVOO_DirectoMarcaVigo.png\" alt=\"\" width=\"916\" height=\"306\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/03\/AVOO_DirectoMarcaVigo.png 916w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/03\/AVOO_DirectoMarcaVigo-320x107.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/03\/AVOO_DirectoMarcaVigo-768x257.png 768w\" sizes=\"(max-width: 916px) 100vw, 916px\" \/><p id=\"caption-attachment-120986\" class=\"wp-caption-text\">Pincha en la imagen y vete al minuto y los segundos que aparecen en la captura de pantalla para escuchar la entrevista.<\/p><\/div>\n<p style=\"text-align: justify;\">Ya sab\u00e9is que desde la\u00a0Facultade de Filolox\u00eda e Traduci\u00f3n de la Universidade de Vigo, participamos en el proyecto <em>Avoo\u00a0<\/em>con la firma de nuestro <a href=\"https:\/\/www.joseyustefrias.com\/2022\/02\/16\/avoo-el-proyecto-de-colaboracion-etiv-iseltec-muvi\/\" target=\"_blank\" rel=\"noopener\">Contrato de Colaboraci\u00f3n Universidad\u2013Empresa<\/a>. Despu\u00e9s de haber iniciado la reinterpretaci\u00f3n del tradicional juego de Trivial autogestionado con un particular dise\u00f1o concebido para jugar de forma intergeneracional (los\/as abuelos\/as con sus nietos\/as), el proyecto\u00a0<em>Avoo<\/em> se encuentra ahora en plena fase de creaci\u00f3n\/innovaci\u00f3n antes de iniciar los planes de comercializaci\u00f3n e internacionalizaci\u00f3n en los que el ETIV del MTCI de la UVigo, adem\u00e1s de realizar las labores de revisi\u00f3n, correcci\u00f3n y posedici\u00f3n de las versiones gallega y espa\u00f1ola originales, llevamos a cabo las labores de traducciones inversas al ingl\u00e9s, al franc\u00e9s y al portugu\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Un \u00faltimo detalle para terminar esta entrada directamente relacionado con la <a href=\"https:\/\/www.joseyustefrias.com\/2012\/01\/18\/tipografia-creativa-para-traducir\/\" target=\"_blank\" rel=\"noopener\">tipograf\u00eda para-traducir<\/a>: si escuch\u00e1is la entrevista, descubrir\u00e9is desde el principio de la misma por qu\u00e9 <em>Av<strong>oo<\/strong><\/em> se escribe con dos \u00abo\u00bb y no con una sola.<\/p>\n<p>J.Y.F.<\/p>","protected":false},"excerpt":{"rendered":"<p>Hoy, Ismael Men\u00e9ndez y Jacobo Mart\u00ednez han sido entrevistados en el programa\u00a0de radio Directo Marca Vigo\u00a0 sobre el proyecto del videojuego Avoo, desarrollado por la empresa coru\u00f1esa Iseltec\u00a0con la colaboraci\u00f3n de la Fundaci\u00f3n Museo do Videoxogo de Galicia (MUVI) y el T\u00edtulo Propio de Especialista en Traducci\u00f3n para la Industria del Videojuego (ETIV) de nuestro\u00a0M\u00e1ster&hellip;<\/p>","protected":false},"author":1,"featured_media":120987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[129],"tags":[145,143,144,142],"_links":{"self":[{"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/posts\/120985"}],"collection":[{"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/comments?post=120985"}],"version-history":[{"count":7,"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/posts\/120985\/revisions"}],"predecessor-version":[{"id":120994,"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/posts\/120985\/revisions\/120994"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/media\/120987"}],"wp:attachment":[{"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/media?parent=120985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/categories?post=120985"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/paratraduccion.com\/limiares\/pt\/wp-json\/wp\/v2\/tags?post=120985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}