{"id":93427,"date":"2020-06-16T06:46:40","date_gmt":"2020-06-16T06:46:40","guid":{"rendered":"http:\/\/paratraduccion.com\/limiares\/?p=93427"},"modified":"2020-06-16T06:46:40","modified_gmt":"2020-06-16T06:46:40","slug":"region-de-murcia-seleccion-de-personal-interino-de-ensenanza-secundaria-para-cubrir-plazas-vacantes-o-sustituciones-para-frances","status":"publish","type":"post","link":"https:\/\/paratraduccion.com\/limiares\/en\/region-de-murcia-seleccion-de-personal-interino-de-ensenanza-secundaria-para-cubrir-plazas-vacantes-o-sustituciones-para-frances\/","title":{"rendered":"Regi\u00f3n de Murcia : selecci\u00f3n de personal interino de ense\u00f1anza secundaria para cubrir plazas vacantes o sustituciones para franc\u00e9s."},"content":{"rendered":"<h3 class=\"ng-binding\" style=\"margin: 0px;width: 1210px;text-align: justify;color: #9e1b32;text-transform: none;line-height: 34px;text-indent: 0px;letter-spacing: normal;padding-top: 0px;padding-right: 20px;padding-bottom: 10px;font-family: 'Open Sans',sans-serif;font-size: 24px;font-style: normal;font-weight: 500;background-color: #ffffff\"><span style=\"color: #000000\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-93429\" src=\"http:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2020\/06\/logo-BORM-320x167.jpg\" alt=\"\" width=\"320\" height=\"167\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2020\/06\/logo-BORM-320x167.jpg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2020\/06\/logo-BORM.jpg 470w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/span><\/h3>\n<h3 style=\"text-align: justify\">Orden de 29 de mayo de 2020 de la Consejer\u00eda de Educaci\u00f3n y Cultura por la que se convoca procedimiento extraordinario para la selecci\u00f3n de personal interino para cubrir plazas vacantes o sustituciones en determinadas especialidades del Cuerpo de Profesores de Ense\u00f1anza Secundaria.<\/h3>\n<p><a href=\"https:\/\/www.borm.es\/#\/home\/anuncio\/13-06-2020\/2823\">Leer m\u00e1s<\/a><\/p>\n<p><a href=\"https:\/\/www.borm.es\/services\/anuncio\/ano\/2020\/numero\/2823\/pdf?id=785303\">Descargar PDF del BORM<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Orden de 29 de mayo de 2020 de la Consejer\u00eda de Educaci\u00f3n y Cultura por la que se convoca procedimiento extraordinario para la selecci\u00f3n de personal interino para cubrir plazas vacantes o sustituciones en determinadas especialidades del Cuerpo de Profesores de Ense\u00f1anza Secundaria. Leer m\u00e1s Descargar PDF del BORM<\/p>","protected":false},"author":4,"featured_media":93430,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93,35],"tags":[],"_links":{"self":[{"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/posts\/93427"}],"collection":[{"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/comments?post=93427"}],"version-history":[{"count":2,"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/posts\/93427\/revisions"}],"predecessor-version":[{"id":93432,"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/posts\/93427\/revisions\/93432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/media\/93430"}],"wp:attachment":[{"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/media?parent=93427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/categories?post=93427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/en\/wp-json\/wp\/v2\/tags?post=93427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}