{"id":47,"date":"2013-03-10T21:41:01","date_gmt":"2013-03-10T21:41:01","guid":{"rendered":"http:\/\/paratraduccion.com\/mestrado\/iolanda-galanes\/"},"modified":"2026-07-02T17:35:12","modified_gmt":"2026-07-02T17:35:12","slug":"iolanda-galanes","status":"publish","type":"page","link":"https:\/\/paratraduccion.com\/limiares\/es\/iolanda-galanes\/","title":{"rendered":"Galanes Santos, Iolanda"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"47\" class=\"elementor elementor-47\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b915a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b915a2\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2dd8468\" data-id=\"2dd8468\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ae7063 elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"8ae7063\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id =\"8ae7063\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\"><div class=\"bdt-ep-advanced-heading-content bdt-visible@m\"><div class=\"bdt-transform-origin-top-left\">Catedr\u00e1tica de universidad<\/div><\/div><h2 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">Catedr\u00e1tica de universidad\n<\/span><\/span><\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae35050 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"ae35050\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-orcid elementor-repeater-item-c2353f3\" href=\"https:\/\/orcid.org\/0000-0002-6149-6068\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Orcid<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-orcid\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-researchgate elementor-repeater-item-f05e487\" href=\"https:\/\/www.researchgate.net\/profile\/Iolanda-Galanes-2\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Researchgate<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-researchgate\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0312602 elementor-widget elementor-widget-bdt-accordion\" data-id=\"0312602\" data-element_type=\"widget\" data-widget_type=\"bdt-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"bdt-ep-accordion-container\">\n            <div id=\"bdt-ep-accordion-0312602\" class=\"bdt-ep-accordion bdt-accordion\" data-bdt-accordion=\"{&quot;collapsible&quot;:true,&quot;multiple&quot;:false,&quot;transition&quot;:&quot;ease-in-out&quot;}\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-accordion-0312602&quot;,&quot;activeHash&quot;:&quot;no&quot;,&quot;activeScrollspy&quot;:null,&quot;hashTopOffset&quot;:false,&quot;hashScrollspyTime&quot;:false}\">\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-bionota\" data-accordion-index=\"0\" data-title=\"bionota\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-plus\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                BIONOTA                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <p style=\"text-align: justify;\" class=\" translation-block\">Iolanda Galanes Santos es doctora en Filolog\u00eda Gallega por la <a href=\"https:\/\/www.usc.gal\/es\" target=\"_self\" role=\"link\">Universidade de Santiago de Compostela<\/a>y realiz\u00f3 estudios de posgrado en la  <a href=\"https:\/\/www.ulaval.ca\/es\" target=\"_self\" role=\"link\">Universidad de Laval<\/a> (Quebec) y en la <a href=\"https:\/\/www.umontreal.ca\/\" target=\"_self\" role=\"link\">Universidad de Montreal<\/a>. Su investigaci\u00f3n se adscribe a dos l\u00edneas: la Terminolog\u00eda en la Traducci\u00f3n especializada, como coordinadora de la l\u00ednea Terminolog\u00eda y Terminograf\u00eda de <a href=\"https:\/\/bifega.webs.uvigo.es\/\" target=\"_self\" role=\"link\">BiFeGa<\/a>, y la Traducci\u00f3n literaria en Galicia, como miembro de <a href=\"https:\/\/bitraga.webs.uvigo.es\/\" target=\"_self\" role=\"link\">BITRAGA<\/a>. Es autora y coautora de varias monografias y de una decena de diccionarios especializados de \u00e1mbito internacional. Participa desde hace dos d\u00e9cadas en congresos internacionales y publica regularmente art\u00edculos acad\u00e9micos sobre las dichas l\u00edneas.<\/p><p style=\"text-align: justify;\" class=\" translation-block\">Cuenta con experiencia profesional como traductora. Entre 1999 y 2005 es coordinadora t\u00e9cnica de la Secci\u00f3n de Lengua del <a href=\"http:\/\/consellodacultura.gal\/\" target=\"_self\" role=\"link\">Consello da Cultura Galega<\/a>, puesto en el que est\u00e1 en excedencia. Actualmente desarrolla su actividad docente sobre Terminolog\u00eda y traducci\u00f3n en la titulaci\u00f3n de Traducci\u00f3n e Interpretaci\u00f3n de la <a href=\"https:\/\/www.uvigo.gal\/es\" target=\"_self\" role=\"link\">Universidade de Vigo<\/a>.<\/p>                        <\/div>\n                    <\/div>\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-experiencia-docente\" data-accordion-index=\"1\" data-title=\"experiencia-docente\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-plus\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                EXPERIENCIA DOCENTE                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <p style=\"text-align: justify;\" class=\" translation-block\">Es profesora titular del Departamento de Traducci\u00f3n y Ling\u00fc\u00edstica de la <a href=\"https:\/\/www.uvigo.gal\/es\" target=\"_self\" role=\"link\">Universidade de Vigo<\/a>, a la que pertenece desde el 2000. Trabaj\u00f3 tambi\u00e9n en la formaci\u00f3n de funcionariado en lenguas de especialidad (<a href=\"https:\/\/egap.xunta.gal\/\" target=\"_self\" role=\"link\">EGAP<\/a>, DXPL, etc.), en planificaci\u00f3n ling\u00fc\u00edstica (<a href=\"https:\/\/ctnl.gal\/\" target=\"_self\" role=\"link\">CTNL<\/a>) y en traducci\u00f3n jur\u00eddico-administrativa (<a href=\"https:\/\/www.agpti.org\/\" target=\"_self\" role=\"link\">AGPTI<\/a>).Imparti\u00f3 docencia en varias universidades extranjeras como participante en programas de intercambio ERASMUS, como coordinadora de programas intensivos (IP KA2) y como profesora visitante en las universidades de Lisboa, P\u00e1dova, S\u00e3o Paulo y Montreal. Es responsable de la formaci\u00f3n en Terminolog\u00eda y Terminograf\u00eda en el grado en Traducci\u00f3n e Interpretaci\u00f3n, as\u00ed como en el <a href=\"https:\/\/paratraduccion.com\/limiares\/\" target=\"_self\" role=\"link\">M\u00e1ster en Traducci\u00f3n para la Comunicaci\u00f3n Internacional<\/a>\u00a0y en el <a href=\"https:\/\/www.uvigo.gal\/es\/estudiar\/que-estudiar\/doctorado\/programa-doutoramento-traducion-paratraducion-v01d024v06\" target=\"_self\" role=\"link\">programa de doctorado Traducci\u00f3n y Paratraducci\u00f3n<\/a>, adem\u00e1s de haber impartido materias de traducci\u00f3n.<\/p>                        <\/div>\n                    <\/div>\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-materias-impartidas-no-mtci\" data-accordion-index=\"2\" data-title=\"materias-impartidas-no-mtci\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-plus\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                MATERIAS IMPARTIDAS EN EL MTCI                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <ul><li><p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/terminoloxia\/\" target=\"_blank\" rel=\"noopener\">Terminolog\u00eda en traducci\u00f3n<\/a><\/p><\/li><\/ul>                        <\/div>\n                    <\/div>\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-lias-de-investigacin\" data-accordion-index=\"3\" data-title=\"li-as-de-investigaci-n\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-plus\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                L\u00cdNEAS DE INVESTIGACI\u00d3N                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <p style=\"text-align: justify;\" class=\" translation-block\">En Traducci\u00f3n literaria destaca su colaboraci\u00f3n en <a href=\"https:\/\/bitraga.webs.uvigo.es\/\" target=\"_self\" role=\"link\">BITRAGA<\/a>, en el <a href=\"http:\/\/bibliotraducion.uvigo.es\/\" target=\"_self\" role=\"link\">Cat\u00e1logo Virtual de la Traducci\u00f3n Gallega<\/a>, del que se derivan publicaciones sobre las relaciones del sistema literario gallego con otras literaturas <a href=\"http:\/\/www.editorialcomares.com\/TV\/articulo\/3111-La_traduccion_literaria.html\" target=\"_self\" role=\"link\"><em>La traducci\u00f3n literaria. Nuevas investigaciones<\/em><\/a> (Comares, 2016), <a href=\"https:\/\/www.peterlang.com\/view\/product\/46248\" target=\"_self\" role=\"link\"><em>Literaturas extranjeras y desarrollo cultural<\/em><\/a> (Peter Lang, 2015) o <a href=\"https:\/\/www.peterlang.com\/view\/product\/44564\" target=\"_self\" role=\"link\"><em>Traducci\u00f3n de una cultura emergente<\/em><\/a> (Peter Lang, 2012), etc. Tambi\u00e9n estudia las estrategias de promoci\u00f3n cultural en las Ferias Internacionales del libro y la traducci\u00f3n de determinados g\u00e9neros literarios. En la l\u00ednea Terminolog\u00eda, es coautora de diccionarios especializados internacionales (ej. <a href=\"http:\/\/www.realiter.net\/wp-content\/uploads\/2013\/06\/manutention.pdf\" target=\"_self\" role=\"link\"><em>Lexique panlatin de manutention et stockage<\/em><\/a>,\u00a0 <a href=\"http:\/\/www.realiter.net\/wp-content\/uploads\/2013\/06\/pan-energie-power.pdf\" target=\"_self\" role=\"link\"><em>L\u00e9xico da enerx\u00eda e\u00f3lica<\/em><\/a><u>)<\/u>.<\/p><p style=\"text-align: justify;\" class=\" translation-block\">Publica regularmente art\u00edculos acad\u00e9micos (<a href=\"https:\/\/revistas.ucm.es\/index.php\/MADR\/article\/view\/56225\" target=\"_self\" role=\"link\">Memorias dun neno labrego: a forxa dun longseller<\/a>, <em>Madrygal<\/em> 20, 2017;\u00a0 <a href=\"https:\/\/benjamins.com\/#catalog\/journals\/babel.61.2.06fer\/details\" target=\"_self\" role=\"link\">La crise hypoth\u00e9caire et ses d\u00e9nominations<\/a>, <em>Babel<\/em> 61:2, 2015; <a href=\"https:\/\/www.researchgate.net\/publication\/281525956_Terminografia_galega_e_calidade_novos_modelos\" target=\"_self\" role=\"link\">Terminograf\u00eda galega e calidade: novos modelos<\/a>, <em>Estudos de Ling\u00fc\u00edstica Galega<\/em> 2015 ou <a href=\"https:\/\/www.researchgate.net\/publication\/281525946_Carlos_Casares_y_la_traduccion_obra_dispersa_e_inedita\" target=\"_self\" role=\"link\">Carlos Casares y la traducci\u00f3n: obra dispersa e in\u00e9dita<\/a>, <em>Quaderns para la traducci\u00f3<\/em> 21, 2014).<\/p>                        <\/div>\n                    <\/div>\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-publicacins\" data-accordion-index=\"4\" data-title=\"publicaci-ns\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-plus\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                PUBLICACIONES                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <ul><li style=\"text-align: justify;\" class=\" translation-block\">Villarino Pardo, C.; Galanes Santos, I. &amp; Luna Alonso, A (eds.) 2021. <em>Promoci\u00f3n cultural y Traducci\u00f3n<\/em>. Peter Lang: Berna. <a href=\"https:\/\/www.peterlang.com\/document\/1142500\" target=\"_self\" role=\"link\">https:\/\/www.peterlang.com\/document\/1142500<\/a><\/li><li style=\"text-align: justify;\">Villarino Pardo, C.; Galanes Santos, I. &amp; Luna Alonso, A (eds.) 2021. <em>Promoci\u00f3n cultural y Traducci\u00f3n<\/em>. Peter Lang: Berna. <a href=\"https:\/\/www.peterlang.com\/document\/1142500\">https:\/\/www.peterlang.com\/document\/1142500<\/a><\/li><li style=\"text-align: justify;\" class=\" translation-block\">Galanes-Santos, Iolanda. 2019. \u201cEl redactor period\u00edstico ante el neologismo. Estrategias comunicativas para reexpresar los conceptos de la crisis econ\u00f3mica mundial.\u201d En <em>Comunicaci\u00f3n, Traducci\u00f3n e Interpretaci\u00f3n \/Communication, Translation and Interpreting. MonTI Special Issue <\/em>5, 122-146. DOI: <a href=\"http:\/\/dx.doi.org\/10.6035\/MonTI.2019.ne5.5\" target=\"_self\" role=\"link\">http:\/\/dx.doi.org\/10.6035\/MonTI.2019.ne5.5<\/a><\/li><li style=\"text-align: justify;\">Galanes-Santos, Iolanda. 2019. \u201cEl redactor period\u00edstico ante el neologismo. Estrategias comunicativas para reexpresar los conceptos de la crisis econ\u00f3mica mundial.\u201d En <em>Comunicaci\u00f3n, Traducci\u00f3n e Interpretaci\u00f3n \/Communication, Translation and Interpreting. MonTI Special Issue <\/em>5, 122-146. DOI: <a href=\"http:\/\/dx.doi.org\/10.6035\/MonTI.2019.ne5.5\">http:\/\/dx.doi.org\/10.6035\/MonTI.2019.ne5.5<\/a><\/li><li style=\"text-align: justify;\" class=\" translation-block\">Galanes Santos, I. 2018. A proxecci\u00f3n exterior da literatura galega e Carlos Casares: obst\u00e1culos e estratexias, <em>Bolet\u00edn Galego de Literatura<\/em>, 53 (2). <a href=\"http:\/\/dx.doi.org\/10.15304\/bgl.53.5032\" target=\"_self\" role=\"link\">http:\/\/dx.doi.org\/10.15304\/bgl.53.5032<\/a><\/li><\/ul>                        <\/div>\n                    <\/div>\n                            <\/div>\n        <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4cced4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4cced4\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e30cd1f\" data-id=\"e30cd1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b793b5d elementor-widget__width-auto elementor-widget elementor-widget-global elementor-global-122536 elementor-widget-premium-addon-person\" data-id=\"b793b5d\" data-element_type=\"widget\" data-settings=\"{&quot;persons_per_row&quot;:&quot;16.667%&quot;,&quot;persons_per_row_tablet&quot;:&quot;100%&quot;,&quot;persons_per_row_mobile&quot;:&quot;100%&quot;}\" data-widget_type=\"premium-addon-person.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"premium-persons-container premium-person-style1 multiple-persons\" data-persons-equal=\"\">\r\n\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"320\" height=\"426\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/lorena_abreu_BG-320x426.png\" class=\"attachment-medium size-medium wp-image-126037\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/lorena_abreu_BG-320x426.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/lorena_abreu_BG-9x12.png 9w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/lorena_abreu_BG.png 433w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tAbreu L\u00f3pez, Lorena\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/abreu-lopez-lorena\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Emmanuel-scaled.jpeg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tBourgoin Vergondy, Emmanuel\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/bourgoin-vergondy-emmanuel-claude\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121672\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tBux\u00e1n Otero, Patricia\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/patricia-bujan\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121670\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tDe Carlos Villamarin, Pablo\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/pablo-de-carlo\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121668\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tDel Pozo Trivi\u00f1o, Maribel\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/del-pozo-maribel\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121671\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tFern\u00e1ndez Carballo Calero, Pablo\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/pablo-fernandez-carballo-calero\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"323\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-320x323.jpeg\" class=\"attachment-medium size-medium wp-image-121660\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-320x323.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-1200x1212.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-768x775.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-1521x1536.jpeg 1521w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-2028x2048.jpeg 2028w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tFern\u00e1ndez Ocampo, Anxo\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/fernandez-ocampo-anxo\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--320x320.jpg\" class=\"attachment-medium size-medium wp-image-121669\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--320x320.jpg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--1200x1200.jpg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--160x160.jpg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--768x768.jpg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--1536x1536.jpg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--2048x2048.jpg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tFerreiro V\u00e1zquez, \u00d3scar\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/oscar-ferreiro-vazquez\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121664\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tGalanes Santos, Iolanda\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/iolanda-galanes\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121685\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tGarrido Vilari\u00f1o, Xo\u00e1n\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/garrido-vilarino-xoan-manuel\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121674\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tGonz\u00e1lez Santamar\u00eda, Pedro\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/pedro-gonzalez\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121665\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tGregori Sendra, Jessica\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/gregori-sendra-jessica\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121658\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tHermida Ruibal, Ana\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/ana-hermida-ruibal\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121677\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tLouredo Casado, Sara\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/sara-louredo-casado\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121659\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tLuna Alonso, Ana\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/ana-luna\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"427\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto-320x427.png\" class=\"attachment-medium size-medium wp-image-128376\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto-320x427.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto-768x1024.png 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto-9x12.png 9w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto.png 844w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tMarta Rodr\u00edguez, Valentina\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/valentina-marta\/\"><span style=\"color: #00ccff;\">BIONOTA<br \/><\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"294\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-320x294.png\" class=\"attachment-medium size-medium wp-image-128353\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-320x294.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-1200x1104.png 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-768x706.png 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-13x12.png 13w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto.png 1385w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tMeiri\u00f1o G\u00f3mez, Jes\u00fas \t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/meirino-gomez-jesus\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121675\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tM\u00e9ndez Gonz\u00e1lez, Ram\u00f3n\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/ramon-mendez\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121678\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tMontero Dom\u00ednguez, Xo\u00e1n\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/xoan-montero\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121676\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tMourelo P\u00e9rez, Salvador\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/mourelo-salvador\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121661\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tSanchez Trigo, Elena\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/elena-sanchez-trigo\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121673\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tSotelo Dios, Patricia\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/sotelo-dios-patricia\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121663\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tTorres P\u00e9rez, Francisco Jos\u00e9\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/franciso-jose-torres-perez\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121666\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tYuste Fr\u00edas, Jos\u00e9\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/es\/yuste-frias\/\"><span style=\"color: #00ccff;\">BIONOTA<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Catedr\u00e1tica de universidade Catedr\u00e1tica de universidade Orcid Researchgate BIONOTA Iolanda Galanes Santos \u00e9 doutora en Filolox\u00eda Galega pola Universidade de Santiago de Compostela e realizou estudos de posgrao na Universidade de Laval (Quebec) e na Universidade de Montreal. A s\u00faa investigaci\u00f3n enc\u00e1drase en d\u00faas li\u00f1as de traballo: a Terminolox\u00eda na Traduci\u00f3n especializada, como coordinadora da&hellip;<\/p>","protected":false},"author":1,"featured_media":121664,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/pages\/47"}],"collection":[{"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":26,"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/pages\/47\/revisions"}],"predecessor-version":[{"id":128441,"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/pages\/47\/revisions\/128441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/media\/121664"}],"wp:attachment":[{"href":"https:\/\/paratraduccion.com\/limiares\/es\/wp-json\/wp\/v2\/media?parent=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}