{"id":121480,"date":"2021-03-06T19:03:14","date_gmt":"2021-03-06T19:03:14","guid":{"rendered":"http:\/\/wandau.themezinho.net\/?page_id=6"},"modified":"2026-06-09T17:22:59","modified_gmt":"2026-06-09T17:22:59","slug":"home","status":"publish","type":"page","link":"https:\/\/paratraduccion.com\/limiares\/fr\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"121480\" class=\"elementor elementor-121480\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f54597 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f54597\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\" data-no-translation=\"\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-352467c\" data-id=\"352467c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e9a344 elementor-widget elementor-widget-slider_revolution\" data-id=\"2e9a344\" data-element_type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Slider fr REVOLUTION SLIDER 6.6.16 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_6_3_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_6_3\" style=\"\" data-version=\"6.6.16\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-8\" data-title=\"Slide\" data-ssop=\"true\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" src=\"\/\/paratraduccion.com\/limiares\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"WEB-MTCI_10\" width=\"2560\" height=\"1696\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/WEB-MTCI_10-scaled.jpg\" data-bg=\"p:50% 87%;\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-6-slide-8-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#ffffff\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"y:49px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:97;l:121;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2846px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:'Cormorant Garamond';\"\n\t\t\t\t\t\t\t><font color=\"black\">Master en Traduction<\/font><br> <font color=\"red\">pour<\/font><br>  <font color=\"black\">la Communication Internationale <\/font><br> <font color=\"red\">(MTCI)<\/font> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-6-slide-8-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:890px;y:730px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:178px;h:100px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/paratraduccion.com\/limiares\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"538\" height=\"303\" data-lazyload=\"\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/EMT-Main-paratraduccion.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-6-slide-8-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:39px;y:746px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:350px;h:100px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/paratraduccion.com\/limiares\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"7000\" height=\"2000\" data-lazyload=\"\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2021\/08\/XUNTA-DE-GALICIA_marca-positivo.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-6-slide-8-layer-3\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#ff0000\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:39px;y:844px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'EB Garamond';\"\n\t\t\t\t\t\t\t>Master Universitaire d'Excellence de la Xunta de Galicia<br \/>\n<br \/>\n \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-6-slide-8-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#ff0000\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:890px;y:844px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'EB Garamond';\"\n\t\t\t\t\t\t\t>European Master\u00b4s In Translation (EMT)<br \/>\n<br \/>\n<br \/>\n \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-9\" data-title=\"Slide\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/paratraduccion.com\/limiares\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/paratraduccion.com\/limiares\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_6_3',rl:[1240,1024,778,480],el:[900],gw:[1240],gh:[900],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider63\"]!==undefined) {window.RS_MODULES.modules[\"revslider63\"].once = false;window.revapi6 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fc5e77 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4fc5e77\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32ad11c\" data-id=\"32ad11c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cf45f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cf45f2\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ed5387d\" data-id=\"ed5387d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d41d50f elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"d41d50f\" data-element_type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;en galego&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-no-translation=\"\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-d41d50f{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f5226b9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f5226b9\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e053bb8\" data-id=\"e053bb8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b7f7b3 elementor-widget elementor-widget-pdfjs_viewer\" data-id=\"8b7f7b3\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"pdfjs_viewer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-8b7f7b3{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b8291 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"e0b8291\" data-element_type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;en espa\\u00f1ol&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-no-translation=\"\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-e0b8291{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca16634 elementor-widget elementor-widget-pdfjs_viewer\" data-id=\"ca16634\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"pdfjs_viewer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-ca16634{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f51347b elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"f51347b\" data-element_type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;English&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-no-translation=\"\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-f51347b{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bf35f4 elementor-widget elementor-widget-pdfjs_viewer\" data-id=\"9bf35f4\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"pdfjs_viewer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-9bf35f4{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07a4d0d elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"07a4d0d\" data-element_type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;Portugu\\u00eas&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-no-translation=\"\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-07a4d0d{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d85eac8 elementor-widget elementor-widget-pdfjs_viewer\" data-id=\"d85eac8\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"pdfjs_viewer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-d85eac8{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27b2fd3 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"27b2fd3\" data-element_type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;fran\\u00e7ais&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-no-translation=\"\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Plaquette en<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">fran\u00e7ais<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b80c399 elementor-widget elementor-widget-pdfjs_viewer\" data-id=\"b80c399\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"pdfjs_viewer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/plugins\/pdf-viewer-for-elementor\/assets\/pdfjs\/web\/viewer.html?file=https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2025\/06\/Triptico-MTCI_FR.pdf&amp;embedded=true\" style=\"display: block; margin-left: auto; margin-right: auto; width: 640px; height: 725px;\" frameborder=\"1\" marginheight=\"0px\" marginwidth=\"0px\" allowfullscreen><\/iframe>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-52a9979 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52a9979\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2322479\" data-id=\"2322479\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7f4d12 elementor-widget elementor-widget-spacer\" data-id=\"e7f4d12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4426463 elementor-widget elementor-widget-the7-heading\" data-id=\"4426463\" data-element_type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"the7-heading-title elementor-size-default\">BLOG<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fca807b elementor-widget elementor-widget-spacer\" data-id=\"fca807b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d85148 elementor-grid-2 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"3d85148\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;2&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-128420 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/paratraduccion.com\/limiares\/fr\/mtci-la-voz\/\" tabindex=\"-1\" target=\"&quot;_blank&quot;\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"704\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/v22c1-e1782129505748.png\" class=\"attachment-full size-full wp-image-128424\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/v22c1-e1782129505748.png 990w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/v22c1-e1782129505748-320x228.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/v22c1-e1782129505748-768x546.png 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/v22c1-e1782129505748-18x12.png 18w\" sizes=\"(max-width: 990px) 100vw, 990px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/mtci-la-voz\/\" target=\"&quot;_blank&quot;\">\n\t\t\t\t\u00d3scar Ferreiro, coordinador do mestrado, destaca os logros do MTCI tras a renovaci\u00f3n da Menci\u00f3n de Excelencia da Xunta de Galicia\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>O M\u00e1ster en Traduci\u00f3n para a Comunicaci\u00f3n Internacional (MTCI) volve situarse entre os mestrados de referencia do eido da traduci\u00f3n. O xornal La Voz de<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/paratraduccion.com\/limiares\/fr\/mtci-la-voz\/\" aria-label=\"Read more about \u00d3scar Ferreiro, coordinador do mestrado, destaca os logros do MTCI tras a renovaci\u00f3n da Menci\u00f3n de Excelencia da Xunta de Galicia\" tabindex=\"-1\" target=\"_blank\">\n\t\t\tEn savoir plus\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-128291 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/paratraduccion.com\/limiares\/fr\/excelencia-2031\/\" tabindex=\"-1\" target=\"&quot;_blank&quot;\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"1625\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Cuberta.jpg\" class=\"attachment-full size-full wp-image-128298\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Cuberta.jpg 1184w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Cuberta-320x439.jpg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Cuberta-768x1054.jpg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Cuberta-1119x1536.jpg 1119w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Cuberta-9x12.jpg 9w\" sizes=\"(max-width: 1184px) 100vw, 1184px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/excelencia-2031\/\" target=\"&quot;_blank&quot;\">\n\t\t\t\tO MTCI renova a menci\u00f3n de Excelencia da Xunta de Galicia ata o 2031 e reafirma o seu liderado no SUG\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Como coordinador do Mestrado en Traduci\u00f3n para a Comunicaci\u00f3n Internacional (MTCI), \u00e9 para min unha enorme satisfacci\u00f3n compartir unha noticia moi especial para toda a<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/paratraduccion.com\/limiares\/fr\/excelencia-2031\/\" aria-label=\"Read more about O MTCI renova a menci\u00f3n de Excelencia da Xunta de Galicia ata o 2031 e reafirma o seu liderado no SUG\" tabindex=\"-1\" target=\"_blank\">\n\t\t\tEn savoir plus\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ec5023 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ec5023\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-095c792\" data-id=\"095c792\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56327fa elementor-widget elementor-widget-the7-heading\" data-id=\"56327fa\" data-element_type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"the7-heading-title elementor-size-default\">CORPS ENSEIGNANT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-906715f elementor-widget elementor-widget-spacer\" data-id=\"906715f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-464da93 elementor-widget__width-auto elementor-widget elementor-widget-global elementor-global-122536 elementor-widget-premium-addon-person\" data-id=\"464da93\" data-element_type=\"widget\" data-settings=\"{&quot;persons_per_row&quot;:&quot;16.667%&quot;,&quot;persons_per_row_tablet&quot;:&quot;100%&quot;,&quot;persons_per_row_mobile&quot;:&quot;100%&quot;}\" data-widget_type=\"premium-addon-person.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"premium-persons-container premium-person-style1 multiple-persons\" data-persons-equal=\"\">\r\n\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"426\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/lorena_abreu_BG-320x426.png\" class=\"attachment-medium size-medium wp-image-126037\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/lorena_abreu_BG-320x426.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/lorena_abreu_BG-9x12.png 9w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/lorena_abreu_BG.png 433w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tAbreu L\u00f3pez, Lorena\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/abreu-lopez-lorena\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Emmanuel-scaled.jpeg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tBourgoin Vergondy, Emmanuel\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/bourgoin-vergondy-emmanuel-claude\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121672\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Buxan--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tBux\u00e1n Otero, Patricia\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/patricia-bujan\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121670\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-de-Carlo--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tDe Carlos Villamarin, Pablo\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/pablo-de-carlo\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121668\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Maribel-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tDel Pozo Trivi\u00f1o, Maribel\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/del-pozo-maribel\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121671\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pablo-Fernandez-Calero--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tFern\u00e1ndez Carballo Calero, Pablo\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/pablo-fernandez-carballo-calero\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"323\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-320x323.jpeg\" class=\"attachment-medium size-medium wp-image-121660\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-320x323.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-1200x1212.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-768x775.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-1521x1536.jpeg 1521w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Anxo-2028x2048.jpeg 2028w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tFern\u00e1ndez Ocampo, Anxo\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/fernandez-ocampo-anxo\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--320x320.jpg\" class=\"attachment-medium size-medium wp-image-121669\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--320x320.jpg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--1200x1200.jpg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--160x160.jpg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--768x768.jpg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--1536x1536.jpg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Oscar-Ferreiro--2048x2048.jpg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tFerreiro V\u00e1zquez, \u00d3scar\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/oscar-ferreiro-vazquez\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121664\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Iolanda-Galanes-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tGalanes Santos, Iolanda\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/iolanda-galanes\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121685\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Garrido--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tGarrido Vilari\u00f1o, Xo\u00e1n\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/garrido-vilarino-xoan-manuel\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121674\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Pedro--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tGonz\u00e1lez Santamar\u00eda, Pedro\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/pedro-gonzalez\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121665\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jessica-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tGregori Sendra, Jessica\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/gregori-sendra-jessica\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121658\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Hermida-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tHermida Ruibal, Ana\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/ana-hermida-ruibal\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121677\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Sara-Louredo--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tLouredo Casado, Sara\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/sara-louredo-casado\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121659\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ana-Luna-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tLuna Alonso, Ana\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/ana-luna\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"427\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto-320x427.png\" class=\"attachment-medium size-medium wp-image-128376\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto-320x427.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto-768x1024.png 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto-9x12.png 9w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/Valentina-Marta_foto.png 844w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tMarta Rodr\u00edguez, Valentina\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/valentina-marta\/\"><span style=\"color: #00ccff;\">INFOS<br \/><\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"294\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-320x294.png\" class=\"attachment-medium size-medium wp-image-128353\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-320x294.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-1200x1104.png 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-768x706.png 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto-13x12.png 13w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/Jesus-Meirino_foto.png 1385w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tMeiri\u00f1o G\u00f3mez, Jes\u00fas \t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/meirino-gomez-jesus\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121675\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Ramon--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tM\u00e9ndez Gonz\u00e1lez, Ram\u00f3n\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/ramon-mendez\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121678\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Xoan-Montero-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tMontero Dom\u00ednguez, Xo\u00e1n\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/xoan-montero\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121676\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Salvador-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tMourelo P\u00e9rez, Salvador\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/mourelo-salvador\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121661\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Elena-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tSanchez Trigo, Elena\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/elena-sanchez-trigo\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121673\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Patricia-Sotelo-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tSotelo Dios, Patricia\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/sotelo-dios-patricia\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121663\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Francisco--2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tTorres P\u00e9rez, Francisco Jos\u00e9\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/franciso-jose-torres-perez\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-container premium-person-zoomin-effect\">\r\n\t\t\t\t\t\t<div class=\"premium-person-image-container\">\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-320x320.jpeg\" class=\"attachment-medium size-medium wp-image-121666\" alt=\"\" srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-320x320.jpeg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-1200x1200.jpeg 1200w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-160x160.jpeg 160w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-768x768.jpeg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-1536x1536.jpeg 1536w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2022\/05\/Jose-Yuste-II-2048x2048.jpeg 2048w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"premium-person-info\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-info-container\">\r\n\t\t\t\t\t\t\t\t\t<span class=\"premium-person-name\">\r\n\t\t\t\t\t\tYuste Fr\u00edas, Jos\u00e9\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-person-content\">\r\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/paratraduccion.com\/limiares\/fr\/yuste-frias\/\"><span style=\"color: #00ccff;\">INFOS<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b42dbd elementor-widget__width-auto elementor-widget elementor-widget-premium-addon-person\" data-id=\"1b42dbd\" data-element_type=\"widget\" data-settings=\"{&quot;persons_per_row&quot;:&quot;16.667%&quot;,&quot;persons_per_row_tablet&quot;:&quot;100%&quot;,&quot;persons_per_row_mobile&quot;:&quot;100%&quot;}\" data-widget_type=\"premium-addon-person.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-element-1b42dbd{display:none !important}<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26a2e20 elementor-widget elementor-widget-spacer\" data-id=\"26a2e20\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d5fb4c elementor-widget elementor-widget-the7-heading\" data-id=\"6d5fb4c\" data-element_type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"the7-heading-title elementor-size-default\">PAYS D'ORIGINE DES \u00c9TUDIANTS DU\u00a0MASTER<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcc5612 elementor-widget elementor-widget-mdp-mapper-elementor\" data-id=\"dcc5612\" data-element_type=\"widget\" data-widget_type=\"mdp-mapper-elementor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Start Mapper for Elementor WordPress Plugin -->\n                        <div class=\"mdp-mapper-elementor-box mdp-mapper-elementor-custom-display-type\" style=\" \"\n                        data-resolution=\"countries\"\n                        data-tooltip-trigger=\"none\"\n                        data-tooltip-font-size=\"\"\n                        data-tooltip-text-bold=\"no\"\n                        data-tooltip-text-italic=\"no\"\n                        data-display-type=\"custom\"\n                        data-map-height=\"\"\n                        data-map-width=\"\"\n                        data-display-mode=\"regions\" \n                        data-inactive-region-color=\"\"\n                        data-background-color=\"\"\n                        data-region-to-display=\"\" \n                         data-regions=\"[{&quot;_id&quot;:&quot;f30783c&quot;,&quot;enable_regions_link&quot;:&quot;&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;Su\\u00edza&quot;,&quot;region_code_name&quot;:&quot;CH&quot;,&quot;__globals__&quot;:{&quot;active_region_color&quot;:&quot;&quot;},&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;ec1530b&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;Alemania&quot;,&quot;region_code_name&quot;:&quot;DE&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;8089613&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;Arxentina&quot;,&quot;region_code_name&quot;:&quot;AR&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;f56f353&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;Espa\\u00f1a&quot;,&quot;region_code_name&quot;:&quot;ES&quot;,&quot;__globals__&quot;:{&quot;active_region_color&quot;:&quot;&quot;},&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;81d737e&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;Brasil&quot;,&quot;region_code_name&quot;:&quot;BR&quot;,&quot;__globals__&quot;:{&quot;active_region_color&quot;:&quot;&quot;},&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;5b8c7c5&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;Francia&quot;,&quot;region_code_name&quot;:&quot;FR&quot;,&quot;__globals__&quot;:{&quot;active_region_color&quot;:&quot;&quot;},&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;1fe1d78&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;KENIA&quot;,&quot;region_code_name&quot;:&quot;KE&quot;,&quot;__globals__&quot;:{&quot;active_region_color&quot;:&quot;&quot;},&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;b532ffe&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;M\\u00c9XICO&quot;,&quot;region_code_name&quot;:&quot;mx&quot;,&quot;__globals__&quot;:{&quot;active_region_color&quot;:&quot;&quot;},&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;e508ae9&quot;,&quot;active_region_color&quot;:&quot;#FF000B&quot;,&quot;active_region_name&quot;:&quot;Per\\u00fa&quot;,&quot;region_code_name&quot;:&quot;pe&quot;,&quot;__globals__&quot;:{&quot;active_region_color&quot;:&quot;&quot;},&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;0740f01&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Rusia&quot;,&quot;region_code_name&quot;:&quot;ru&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;12f1cd9&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Philippines&quot;,&quot;region_code_name&quot;:&quot;PH&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;e20f875&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Morocco&quot;,&quot;region_code_name&quot;:&quot;MA&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;9ac1a01&quot;,&quot;active_region_color&quot;:&quot;#FF0101&quot;,&quot;active_region_name&quot;:&quot;China&quot;,&quot;region_code_name&quot;:&quot;CN&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;6f12042&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Italia&quot;,&quot;region_code_name&quot;:&quot;IT&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;aa42f0b&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Portugal&quot;,&quot;region_code_name&quot;:&quot;pt&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;2141fdc&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;EEUU&quot;,&quot;region_code_name&quot;:&quot;us&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;218bcd5&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;India&quot;,&quot;region_code_name&quot;:&quot;in&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;9c561b3&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Egipto&quot;,&quot;region_code_name&quot;:&quot;eg&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;d2e90cd&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Benin&quot;,&quot;region_code_name&quot;:&quot;BJ&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;927b1db&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Pa\\u00edses Bajos&quot;,&quot;region_code_name&quot;:&quot;NL&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;f5ee796&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Ucrania&quot;,&quot;region_code_name&quot;:&quot;ua&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;f88ef72&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Venezuela&quot;,&quot;region_code_name&quot;:&quot;VE&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;ebeaeef&quot;,&quot;active_region_color&quot;:&quot;#FF0000&quot;,&quot;active_region_name&quot;:&quot;Cuba&quot;,&quot;region_code_name&quot;:&quot;CU&quot;,&quot;enable_regions_link&quot;:&quot;no&quot;,&quot;regions_link&quot;:null,&quot;region_tooltip_content&quot;:&quot;&quot;}]\" \n                    data-region-color-axis=\"null\" \n                    data-region-enable-legend=\"\"\n                    data-region-legend-color=\"\"\n                    data-region-legend-font-size=\"\"\n                    data-region-legend-bold-text=\"\"\n                    data-region-legend-italic-text=\"\"\n                    data-region-value-title=\"\"\n                    data-region-additional-value-title=\"\" \n                         \n                         >\n                            <div class=\"mdp-mapper-elementor-map-wrapper\"><\/div>\n                            \n                        <\/div>\n                        <!-- End Mapper for Elementor WordPress Plugin -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26bcbe7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26bcbe7\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-94321e7\" data-id=\"94321e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15565b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15565b1\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b5378f\" data-id=\"3b5378f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c83fce elementor-widget elementor-widget-the7-heading\" data-id=\"1c83fce\" data-element_type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"the7-heading-title elementor-size-default\">T\u00e9moignages des \u00e9tudiants<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc31c87 arrows-relative-to-box_area bullets-small-dot-stroke elementor-widget elementor-widget-the7_testimonials_carousel\" data-id=\"fc31c87\" data-element_type=\"widget\" data-widget_type=\"the7_testimonials_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"carousel-nav-display-always   disable-arrows-hover-bg owl-carousel testimonials-carousel elementor-owl-carousel-call the7-elementor-widget the7_testimonials_carousel-fc31c87 quick-scale-img\" data-scroll-mode=\"1\" data-col-num=\"2\" data-wide-col-num=\"\" data-laptop-col=\"2\" data-h-tablet-columns-num=\"2\" data-v-tablet-columns-num=\"2\" data-phone-columns-num=\"1\" data-auto-height=\"false\" data-col-gap=\"35\" data-col-gap-tablet=\"\" data-col-gap-mobile=\"\" data-speed=\"600\" data-autoplay=\"false\" data-autoplay_speed=\"\"><div  class=\"dt-owl-item-wrap hide-btn elements-hover\"  ><div class=\"dt-owl-item-inner\"><div  class=\"dt-owl-item-image layzr-bg img-css-resize-wrapper\"> <img decoding=\"async\" width=\"802\" height=\"1024\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%20802%201024&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 802px) 100vw, 802px\" style=\"--ratio: 802 \/ 1024;\" data-src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/image_6487327.jpg\" loading=\"eager\" data-srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/image_6487327.jpg 802w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/image_6487327-320x409.jpg 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/image_6487327-768x981.jpg 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/07\/image_6487327-9x12.jpg 9w\" \/><\/div><h3  class=\"dt-owl-item-heading\">Maureen Jebiwot Kimokiy<\/h3><div class=\"dt-owl-item-description\"><p style=\"text-align: justify\">El m\u00e1ster ofrec\u00eda una amplia variedad de materias y profesores dispuestos a compartir sus experiencias tanto acad\u00e9micas como profesionales. Ha sido un a\u00f1o en el que he adquirido un gran conocimiento sobre la traducci\u00f3n, que ha contribuido a que me sienta preparada para lanzarme al mundo de la traducci\u00f3n.<\/p><\/div><\/div><\/div><div  class=\"dt-owl-item-wrap hide-btn elements-hover\"  ><div class=\"dt-owl-item-inner\"><div  class=\"dt-owl-item-image layzr-bg img-css-resize-wrapper\"> <img decoding=\"async\" width=\"410\" height=\"419\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%20410%20419&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 410px) 100vw, 410px\" style=\"--ratio: 410 \/ 419;\" data-src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/09\/Foto-Maria-Herrero-1.png\" loading=\"eager\" data-srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/09\/Foto-Maria-Herrero-1.png 410w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/09\/Foto-Maria-Herrero-1-320x327.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2024\/09\/Foto-Maria-Herrero-1-12x12.png 12w\" \/><\/div><h3  class=\"dt-owl-item-heading\">Mar\u00eda Herrero Prado<\/h3><div class=\"dt-owl-item-description\"><p style=\"text-align: justify\">Entr\u00e9 muy ilusionada y con algo de miedo a tener las expectativas demasiado altas, pero nada m\u00e1s lejos de la realidad. Adem\u00e1s de contar con excelentes profesores y personas, las asignaturas son realmente \u00fatiles, se nos facilitaron cursos para ampliar nuestros conocimientos de forma completamente gratuita e incluso un programa de mentor\u00eda para ayudarnos a tener las riendas desde el inicio de nuestras carreras profesionales. Sin duda, una experiencia que recomiendo para todas aquellas personas que busquen mejorar para ser la mejor versi\u00f3n de s\u00ed mismos, ya que es la filosof\u00eda que siguen desde el MTCI.<\/p><\/div><\/div><\/div><div  class=\"dt-owl-item-wrap hide-btn elements-hover\"  ><div class=\"dt-owl-item-inner\"><div  class=\"dt-owl-item-image layzr-bg img-css-resize-wrapper\"> <img decoding=\"async\" width=\"480\" height=\"491\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%20480%20491&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 480px) 100vw, 480px\" style=\"--ratio: 480 \/ 491;\" data-src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2025\/07\/Captura-de-pantalla-2025-07-10-183118.png\" loading=\"eager\" data-srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2025\/07\/Captura-de-pantalla-2025-07-10-183118.png 480w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2025\/07\/Captura-de-pantalla-2025-07-10-183118-320x327.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2025\/07\/Captura-de-pantalla-2025-07-10-183118-12x12.png 12w\" \/><\/div><h3  class=\"dt-owl-item-heading\">Sof\u00eda Rizzo<\/h3><div class=\"dt-owl-item-description\"><p style=\"text-align: justify\">Mi enriquecedora experiencia de movilidad internacional en la Universidad de Vigo era justo lo que necesitaba para acabar mis estudios con buena nota. No s\u00f3lo fue maravilloso explorar una parte del mundo tan especial como Galicia, sino que adem\u00e1s el MTCI me pareci\u00f3 un entorno incre\u00edblemente estimulante a nivel acad\u00e9mico y, al mismo tiempo, acogedor a nivel humano. Me siento muy afortunada de haber podido aprovechar la novedosa doble titulaci\u00f3n entre nuestras universidades [la UVigo y la UNIPA], ya que me ha permitido viajar sin retrasar mi carrera universitaria, \u00a1sino todo lo contrario!<\/p><\/div><\/div><\/div><div  class=\"dt-owl-item-wrap hide-btn elements-hover\"  ><div class=\"dt-owl-item-inner\"><div  class=\"dt-owl-item-image layzr-bg img-css-resize-wrapper\"> <img decoding=\"async\" width=\"934\" height=\"1125\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%20934%201125&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 934px) 100vw, 934px\" style=\"--ratio: 934 \/ 1125;\" data-src=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/alex-arias.png\" loading=\"eager\" data-srcset=\"https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/alex-arias.png 934w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/alex-arias-320x385.png 320w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/alex-arias-768x925.png 768w, https:\/\/paratraduccion.com\/limiares\/wp-content\/uploads\/2026\/06\/alex-arias-10x12.png 10w\" \/><\/div><h3  class=\"dt-owl-item-heading\">Alex Arias Cabarcos<\/h3><div class=\"dt-owl-item-description\"><p style=\"text-align: justify\">Considero que mi experiencia este curso con la titulaci\u00f3n, el personal de la facultad y el resto del alumnado ha sido muy positiva para m\u00ed. Al venir de un grado en filolog\u00eda, buscaba compensar la falta de formaci\u00f3n espec\u00edfica para dedicarme profesionalmente a la traducci\u00f3n, y el MTCI ha cumplido mis expectativas a este respecto. Las distintas optativas me han permitido, adem\u00e1s, profundizar en especialidades que me interesan especialmente, como la localizaci\u00f3n de videojuegos, la TAV y la traducci\u00f3n jur\u00eddica.<\/p><\/div><\/div><\/div><\/div><div class=\"owl-nav disabled\"><a class=\"owl-prev\" role=\"button\"><i class=\"fas fa-chevron-left\"><\/i><\/a><a class=\"owl-next\" role=\"button\"><i class=\"fas fa-chevron-right\"><\/i><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Tr\u00edptico en espa\u00f1ol BLOG PROFESORADO Abreu L\u00f3pez, Lorena BIONOTA Bourgoin Vergondy, Emmanuel BIONOTA Bux\u00e1n Otero, Patricia BIONOTA De Carlos Villamarin, Pablo BIONOTA Del Pozo Trivi\u00f1o, Maribel BIONOTA Dom\u00ednguez Ara\u00fajo, Lara BIONOTA Fern\u00e1ndez Carballo Calero, Pablo BIONOTA Fern\u00e1ndez Ocampo, Anxo BIONOTA Ferreiro V\u00e1zquez, \u00d3scar BIONOTA Galanes Santos, Iolanda BIONOTA Garrido Vilari\u00f1o, Xo\u00e1n BIONOTA Gonz\u00e1lez Santamar\u00eda, Pedro&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/paratraduccion.com\/limiares\/fr\/wp-json\/wp\/v2\/pages\/121480"}],"collection":[{"href":"https:\/\/paratraduccion.com\/limiares\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paratraduccion.com\/limiares\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paratraduccion.com\/limiares\/fr\/wp-json\/wp\/v2\/comments?post=121480"}],"version-history":[{"count":597,"href":"https:\/\/paratraduccion.com\/limiares\/fr\/wp-json\/wp\/v2\/pages\/121480\/revisions"}],"predecessor-version":[{"id":128380,"href":"https:\/\/paratraduccion.com\/limiares\/fr\/wp-json\/wp\/v2\/pages\/121480\/revisions\/128380"}],"wp:attachment":[{"href":"https:\/\/paratraduccion.com\/limiares\/fr\/wp-json\/wp\/v2\/media?parent=121480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}